{"id":306,"date":"2023-01-12T18:06:18","date_gmt":"2023-01-12T17:06:18","guid":{"rendered":"https:\/\/api-colomiers.com\/victorhugo\/?p=306"},"modified":"2023-01-25T09:02:29","modified_gmt":"2023-01-25T08:02:29","slug":"dates-des-conseils-de-classes-du-1er-semestre-2022-2023","status":"publish","type":"post","link":"https:\/\/api-colomiers.com\/victorhugo\/dates-des-conseils-de-classes-du-1er-semestre-2022-2023\/","title":{"rendered":"Mise \u00e0 jour ! Dates des conseils de classes du 1er semestre 2022-2023"},"content":{"rendered":"\n<p class=\"has-vivid-red-color has-text-color\">Mise \u00e0 jour ! le conseil de classe des 4e1 est d\u00e9cal\u00e9 \u00e0 12h45 le mardi 7 f\u00e9vrier au lieu de 18h30 le jeudi 9 f\u00e9vrier.<\/p>\n\n\n\n<p>Voici les dates des conseils de classes du 1er semestre 2022-2023. <\/p>\n\n\n\n<p><strong>Arr\u00eat des notes et comp\u00e9tences :<\/strong> jeudi 26 janvier \u00e0 18h.<\/p>\n\n\n\n<p>Pour toute question, remarque \u00e0 remonter au conseil ou besoin sp\u00e9cifique \u00e0 votre enfant, n&rsquo;h\u00e9sitez pas \u00e0 nous contacter par email \u00e0 <a rel=\"noreferrer noopener\" href=\"mailto:api.collegevictorhugo@gmail.com\" target=\"_blank\">api.collegevictorhugo@gmail.com<\/a>.<\/p>\n\n\n\n<p>Vous ne savez pas qui est d\u00e9l\u00e9gu\u00e9 pour la classe de votre enfant ? <a rel=\"noreferrer noopener\" href=\"https:\/\/api-colomiers.com\/victorhugo\/lequipe\/\" data-type=\"page\" data-id=\"67\" target=\"_blank\">Voici la liste<\/a>. <\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"956\" height=\"247\" src=\"http:\/\/api-colomiers.com\/victorhugo\/wp-content\/uploads\/2023\/01\/cdc2022s1maj.jpg\" alt=\"\" class=\"wp-image-317\" srcset=\"https:\/\/api-colomiers.com\/victorhugo\/wp-content\/uploads\/2023\/01\/cdc2022s1maj.jpg 956w, https:\/\/api-colomiers.com\/victorhugo\/wp-content\/uploads\/2023\/01\/cdc2022s1maj-300x78.jpg 300w, https:\/\/api-colomiers.com\/victorhugo\/wp-content\/uploads\/2023\/01\/cdc2022s1maj-768x198.jpg 768w\" sizes=\"auto, (max-width: 956px) 100vw, 956px\" \/><\/figure>\n\n\n\n<p><a href=\"https:\/\/victor-hugo.ecollege.haute-garonne.fr\/le-college\/planning-conseil-de-classe-s1-22-23-18259.htm\" data-type=\"URL\" data-id=\"https:\/\/victor-hugo.ecollege.haute-garonne.fr\/le-college\/planning-conseil-de-classe-s1-22-23-18259.htm\">Retrouvez  le planning <\/a><a href=\"https:\/\/victor-hugo.ecollege.haute-garonne.fr\/le-college\/planning-conseil-de-classe-s1-22-23-18259.htm\" data-type=\"URL\" data-id=\"https:\/\/victor-hugo.ecollege.haute-garonne.fr\/le-college\/planning-conseil-de-classe-s1-22-23-18259.htm\" target=\"_blank\" rel=\"noreferrer noopener\">sur <\/a><a href=\"https:\/\/victor-hugo.ecollege.haute-garonne.fr\/le-college\/planning-conseil-de-classe-s1-22-23-18259.htm\" data-type=\"URL\" data-id=\"https:\/\/victor-hugo.ecollege.haute-garonne.fr\/le-college\/planning-conseil-de-classe-s1-22-23-18259.htm\">l&rsquo;ENT<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Voici les dates des conseils de classes du 1er semestre 2022-2023. Pour toute question, remarque \u00e0 remonter au conseil ou besoin sp\u00e9cifique \u00e0 votre enfant, n&rsquo;h\u00e9sitez pas \u00e0 nous contacter !<\/p>\n","protected":false},"author":3,"featured_media":309,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_analysis_target_kw":"","footnotes":""},"categories":[14],"tags":[27],"class_list":["post-306","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vie-au-college","tag-conseil-de-classes"],"_links":{"self":[{"href":"https:\/\/api-colomiers.com\/victorhugo\/wp-json\/wp\/v2\/posts\/306","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/api-colomiers.com\/victorhugo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/api-colomiers.com\/victorhugo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/api-colomiers.com\/victorhugo\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/api-colomiers.com\/victorhugo\/wp-json\/wp\/v2\/comments?post=306"}],"version-history":[{"count":5,"href":"https:\/\/api-colomiers.com\/victorhugo\/wp-json\/wp\/v2\/posts\/306\/revisions"}],"predecessor-version":[{"id":318,"href":"https:\/\/api-colomiers.com\/victorhugo\/wp-json\/wp\/v2\/posts\/306\/revisions\/318"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/api-colomiers.com\/victorhugo\/wp-json\/wp\/v2\/media\/309"}],"wp:attachment":[{"href":"https:\/\/api-colomiers.com\/victorhugo\/wp-json\/wp\/v2\/media?parent=306"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/api-colomiers.com\/victorhugo\/wp-json\/wp\/v2\/categories?post=306"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/api-colomiers.com\/victorhugo\/wp-json\/wp\/v2\/tags?post=306"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}