{"id":1124,"date":"2026-01-18T18:43:00","date_gmt":"2026-01-18T17:43:00","guid":{"rendered":"https:\/\/api-colomiers.com\/victorhugo\/?p=1124"},"modified":"2026-01-20T23:44:17","modified_gmt":"2026-01-20T22:44:17","slug":"relai-petition-api-helene-boucher","status":"publish","type":"post","link":"https:\/\/api-colomiers.com\/victorhugo\/relai-petition-api-helene-boucher\/","title":{"rendered":"Relai p\u00e9tition API H\u00e9l\u00e8ne Boucher"},"content":{"rendered":"\n<p>Pour aider une famille dont les enfants sont scolaris\u00e9s \u00e0 l&rsquo;\u00e9cole H\u00e9l\u00e8ne Boucher \u00e0 Colomiers, le r\u00e9seau API relaye une p\u00e9tition lanc\u00e9e par les parents de l&rsquo;API H\u00e9l\u00e8ne Boucher. Cette p\u00e9tition demande la suspension de l\u2019expulsion et un d\u00e9lai humanitaire pour permettre \u00e0 la famille de trouver une solution d\u2019h\u00e9bergement. Cette famille, une m\u00e8re avec 2 enfants dont un en situation de handicap, est en demande d&rsquo;asile et se retrouve menac\u00e9e d&rsquo;expulsion en pleine tr\u00eave hivernale. <\/p>\n\n\n\n<p>Vous pouvez soutenir cette d\u00e9marche en ajoutant votre signature \u00e0 la p\u00e9tition\u270d\ufe0f: <a href=\"https:\/\/c.org\/5rTzn2RXC5\">https:\/\/c.org\/5rTzn2RXC5<\/a> <\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"819\" height=\"1024\" src=\"https:\/\/api-colomiers.com\/victorhugo\/wp-content\/uploads\/2026\/01\/Petition_API_HB-819x1024.jpeg\" alt=\"\" class=\"wp-image-1127\" style=\"aspect-ratio:0.799815831880817;width:308px;height:auto\" srcset=\"https:\/\/api-colomiers.com\/victorhugo\/wp-content\/uploads\/2026\/01\/Petition_API_HB-819x1024.jpeg 819w, https:\/\/api-colomiers.com\/victorhugo\/wp-content\/uploads\/2026\/01\/Petition_API_HB-240x300.jpeg 240w, https:\/\/api-colomiers.com\/victorhugo\/wp-content\/uploads\/2026\/01\/Petition_API_HB-768x960.jpeg 768w, https:\/\/api-colomiers.com\/victorhugo\/wp-content\/uploads\/2026\/01\/Petition_API_HB.jpeg 1024w\" sizes=\"auto, (max-width: 819px) 100vw, 819px\" \/><\/figure>\n\n\n\n<p>Plus d&rsquo;informations sur le site de la p\u00e9tition en ligne. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pour aider une famille dont les enfants sont scolaris\u00e9s \u00e0 l&rsquo;\u00e9cole H\u00e9l\u00e8ne Boucher \u00e0 Colomiers, le r\u00e9seau API relaye une p\u00e9tition lanc\u00e9e par les parents de l&rsquo;API H\u00e9l\u00e8ne Boucher. Cette p\u00e9tition demande la suspension de l\u2019expulsion et un d\u00e9lai humanitaire<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"none","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_analysis_target_kw":"","footnotes":""},"categories":[7],"tags":[],"class_list":["post-1124","post","type-post","status-publish","format-standard","hentry","category-internet"],"_links":{"self":[{"href":"https:\/\/api-colomiers.com\/victorhugo\/wp-json\/wp\/v2\/posts\/1124","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/api-colomiers.com\/victorhugo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/api-colomiers.com\/victorhugo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/api-colomiers.com\/victorhugo\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/api-colomiers.com\/victorhugo\/wp-json\/wp\/v2\/comments?post=1124"}],"version-history":[{"count":1,"href":"https:\/\/api-colomiers.com\/victorhugo\/wp-json\/wp\/v2\/posts\/1124\/revisions"}],"predecessor-version":[{"id":1128,"href":"https:\/\/api-colomiers.com\/victorhugo\/wp-json\/wp\/v2\/posts\/1124\/revisions\/1128"}],"wp:attachment":[{"href":"https:\/\/api-colomiers.com\/victorhugo\/wp-json\/wp\/v2\/media?parent=1124"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/api-colomiers.com\/victorhugo\/wp-json\/wp\/v2\/categories?post=1124"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/api-colomiers.com\/victorhugo\/wp-json\/wp\/v2\/tags?post=1124"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}